{"id":11326,"date":"2026-05-09T18:28:46","date_gmt":"2026-05-09T18:28:46","guid":{"rendered":"https:\/\/lereveil224.info\/?p=11326"},"modified":"2026-05-09T18:28:48","modified_gmt":"2026-05-09T18:28:48","slug":"kaloum-voici-les-causes-de-lincendie-sur-le-site-de-lancien-depot-dhydrocarbures","status":"publish","type":"post","link":"https:\/\/lereveil224.info\/index.php\/2026\/05\/09\/kaloum-voici-les-causes-de-lincendie-sur-le-site-de-lancien-depot-dhydrocarbures\/","title":{"rendered":"Kaloum : voici les causes de l\u2019incendie sur le site de l\u2019ancien d\u00e9p\u00f4t d\u2019hydrocarbures"},"content":{"rendered":"\n<p>Une nouvelle alerte a sem\u00e9 l\u2019inqui\u00e9tude ce samedi 9 mai 2026 dans la presqu\u2019\u00eele de Kaloum. Un incendie s\u2019est d\u00e9clar\u00e9 sur le site de l\u2019ancien d\u00e9p\u00f4t d\u2019hydrocarbures, ravivant les souvenirs encore vifs de la catastrophe de d\u00e9cembre 2023. Rapidement ma\u00eetris\u00e9 par les \u00e9quipes de secours, le sinistre a toutefois suscit\u00e9 de nombreuses interrogations au sein de la population de Conakry.<\/p>\n\n\n\n<p>Face \u00e0 la presse, le directeur r\u00e9gional de la Protection civile de Conakry, le colonel Ibrahima Sory Kaba, a expliqu\u00e9 que l\u2019incendie serait li\u00e9 \u00e0 des r\u00e9sidus de carburant rest\u00e9s dans certaines installations depuis l\u2019explosion survenue en d\u00e9cembre 2023.<br>Selon lui, apr\u00e8s la violente explosion qui avait ravag\u00e9 le d\u00e9p\u00f4t il y a plus de deux ans, une petite quantit\u00e9 de carburant \u00e9tait demeur\u00e9e dans certains bacs m\u00e9talliques, qui n\u2019avaient pas \u00e9t\u00e9 enti\u00e8rement vid\u00e9s. Ce sont ces r\u00e9sidus qui auraient pris feu lors des op\u00e9rations en cours sur le site.<\/p>\n\n\n\n<p>Au moment du drame, des agents intervenaient dans le cadre d\u2019une op\u00e9ration de nettoyage et de d\u00e9mant\u00e8lement men\u00e9e en collaboration avec le minist\u00e8re de l\u2019Environnement. Des travaux de d\u00e9coupage de structures m\u00e9talliques \u00e9taient en cours, notamment le d\u00e9placement d\u2019\u00e9paves et la coupe de bacs \u00e0 l\u2019aide de cisailles. Les \u00e9tincelles provoqu\u00e9es par ces outils auraient d\u00e9clench\u00e9 le d\u00e9part de feu au contact des restes de carburant encore pr\u00e9sents.<\/p>\n\n\n\n<p>Aussit\u00f4t alert\u00e9e, la Protection civile a d\u00e9ploy\u00e9 ses premi\u00e8res \u00e9quipes pour contenir rapidement les flammes. Des renforts ont ensuite \u00e9t\u00e9 mobilis\u00e9s afin de proc\u00e9der \u00e0 l\u2019extinction compl\u00e8te de l\u2019incendie et s\u00e9curiser la zone.<\/p>\n\n\n\n<p>Malgr\u00e9 l\u2019importante fum\u00e9e noire qui s\u2019est \u00e9lev\u00e9e dans le ciel de Kaloum et a suscit\u00e9 l\u2019inqui\u00e9tude des riverains, les autorit\u00e9s se veulent rassurantes. Le colonel Ibrahima Sory Kaba a indiqu\u00e9 qu\u2019aucune perte en vie humaine ni bless\u00e9 n\u2019est \u00e0 d\u00e9plorer. Les d\u00e9g\u00e2ts se limitent \u00e0 des dommages mat\u00e9riels sur le bac contamin\u00e9.<\/p>\n\n\n\n<p>Ce nouvel incident relance toutefois les interrogations sur la s\u00e9curisation compl\u00e8te du site de l\u2019ancien d\u00e9p\u00f4t, d\u00e9j\u00e0 marqu\u00e9 par l\u2019explosion dramatique de 2023. Les autorit\u00e9s assurent que toutes les mesures n\u00e9cessaires seront prises pour \u00e9viter qu\u2019un tel \u00e9v\u00e9nement ne se reproduise.<\/p>\n\n\n\n<p><strong>Mamadouba CAMARA pour lereveil224.info<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une nouvelle alerte a sem\u00e9 l\u2019inqui\u00e9tude ce samedi 9 mai 2026 dans la presqu\u2019\u00eele de Kaloum. Un incendie s\u2019est d\u00e9clar\u00e9 sur le site de l\u2019ancien d\u00e9p\u00f4t d\u2019hydrocarbures, ravivant les souvenirs encore vifs de la catastrophe de d\u00e9cembre 2023. Rapidement ma\u00eetris\u00e9 par les \u00e9quipes de secours, le sinistre a toutefois suscit\u00e9 de nombreuses interrogations au sein [&hellip;]<\/p>\n","protected":false},"author":123458,"featured_media":11328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,18],"tags":[],"class_list":["post-11326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-region"],"acf":[],"_links":{"self":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts\/11326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/users\/123458"}],"replies":[{"embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/comments?post=11326"}],"version-history":[{"count":1,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts\/11326\/revisions"}],"predecessor-version":[{"id":11327,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts\/11326\/revisions\/11327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/media\/11328"}],"wp:attachment":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/media?parent=11326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/categories?post=11326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/tags?post=11326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}