{"id":11320,"date":"2026-05-09T14:01:25","date_gmt":"2026-05-09T14:01:25","guid":{"rendered":"https:\/\/lereveil224.info\/?p=11320"},"modified":"2026-05-09T14:02:12","modified_gmt":"2026-05-09T14:02:12","slug":"kaloum-incendie-au-depot-de-carburant-de-coronthie-une-epaisse-fumee-noire-visible-dans-le-cielq","status":"publish","type":"post","link":"https:\/\/lereveil224.info\/index.php\/2026\/05\/09\/kaloum-incendie-au-depot-de-carburant-de-coronthie-une-epaisse-fumee-noire-visible-dans-le-cielq\/","title":{"rendered":"Kaloum : incendie au d\u00e9p\u00f4t de carburant de Coronthie, une \u00e9paisse fum\u00e9e noire visible dans le cielq"},"content":{"rendered":"\n<p>Une \u00e9paisse fum\u00e9e noire a sem\u00e9 l\u2019inqui\u00e9tude ce samedi 9 mai 2026 dans la presqu\u2019\u00eele de Kaloum. En cause, un incendie signal\u00e9 sur les installations de l\u2019ancien d\u00e9p\u00f4t d\u2019hydrocarbures du quartier Coronthie, dans la commune de Kaloum.<\/p>\n\n\n\n<p>Selon des informations recueillies aupr\u00e8s de sources officielles, une ancienne cuve contenant du gaz aurait pris feu dans la matin\u00e9e. Tr\u00e8s vite, une colonne de fum\u00e9e dense et sombre a \u00e9t\u00e9 aper\u00e7ue \u00e0 plusieurs kilom\u00e8tres \u00e0 la ronde, suscitant interrogations et inqui\u00e9tudes chez les riverains. Certains habitants, encore marqu\u00e9s par le drame de d\u00e9cembre 2023, ont redout\u00e9 un nouvel incident majeur.<\/p>\n\n\n\n<p>Mais du c\u00f4t\u00e9 des autorit\u00e9s, le discours se veut rassurant. \u00ab L\u2019incendie est d\u00e9j\u00e0 ma\u00eetris\u00e9 \u00bb, a confi\u00e9 une source proche du dossier. Les \u00e9quipes d\u2019intervention se seraient rapidement d\u00e9ploy\u00e9es sur les lieux pour circonscrire les flammes et \u00e9viter toute propagation vers d\u2019autres installations sensibles.<\/p>\n\n\n\n<p>Ce nouvel incident intervient dans un contexte encore fragile pour le secteur \u00e9nerg\u00e9tique guin\u00e9en. Depuis l\u2019explosion du principal d\u00e9p\u00f4t d\u2019hydrocarbures en d\u00e9cembre 2023, le pays fait face \u00e0 des difficult\u00e9s sporadiques d\u2019approvisionnement en carburant. Chaque alerte li\u00e9e \u00e0 des infrastructures p\u00e9troli\u00e8res ravive ainsi les craintes d\u2019une nouvelle perturbation sur le march\u00e9.<\/p>\n\n\n\n<p>Toutefois, les autorit\u00e9s insistent sur le fait qu\u2019il n\u2019y a \u00ab pas lieu de paniquer \u00bb. La situation serait sous contr\u00f4le et ne pr\u00e9senterait, \u00e0 ce stade, aucun risque majeur pour les populations environnantes. Aucune information officielle ne fait \u00e9tat de victimes ni de d\u00e9g\u00e2ts mat\u00e9riels importants.<\/p>\n\n\n\n<p>En attendant un communiqu\u00e9 d\u00e9taill\u00e9 des services comp\u00e9tents, la vigilance reste de mise dans la zone. Les habitants, eux, esp\u00e8rent que cet incident ne viendra pas aggraver une conjoncture d\u00e9j\u00e0 d\u00e9licate.<\/p>\n\n\n\n<p><em>Nous y reviendrons.<\/em><\/p>\n\n\n\n<p><strong>Mamadouba CAMARA pour lereveil224.info<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9paisse fum\u00e9e noire a sem\u00e9 l\u2019inqui\u00e9tude ce samedi 9 mai 2026 dans la presqu\u2019\u00eele de Kaloum. En cause, un incendie signal\u00e9 sur les installations de l\u2019ancien d\u00e9p\u00f4t d\u2019hydrocarbures du quartier Coronthie, dans la commune de Kaloum. Selon des informations recueillies aupr\u00e8s de sources officielles, une ancienne cuve contenant du gaz aurait pris feu dans [&hellip;]<\/p>\n","protected":false},"author":123458,"featured_media":11322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,18],"tags":[],"class_list":["post-11320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","category-region"],"acf":[],"_links":{"self":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts\/11320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/users\/123458"}],"replies":[{"embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/comments?post=11320"}],"version-history":[{"count":1,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts\/11320\/revisions"}],"predecessor-version":[{"id":11321,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/posts\/11320\/revisions\/11321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/media\/11322"}],"wp:attachment":[{"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/media?parent=11320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/categories?post=11320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lereveil224.info\/index.php\/wp-json\/wp\/v2\/tags?post=11320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}